{"id":1868,"count":7,"description":"","link":"https:\/\/blog.wu.ac.at\/en\/tag\/diversitaet-en\/","name":"Diversit\u00e4t","slug":"diversitaet-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diversit\u00e4t Archives - WU Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wu.ac.at\/en\/tag\/diversitaet-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diversit\u00e4t Archives - WU Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wu.ac.at\/en\/tag\/diversitaet-en\/\" \/>\n<meta property=\"og:site_name\" content=\"WU Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.wu.ac.at\\\/en\\\/tag\\\/diversitaet-en\\\/\",\"url\":\"https:\\\/\\\/blog.wu.ac.at\\\/en\\\/tag\\\/diversitaet-en\\\/\",\"name\":\"Diversit\u00e4t Archives - WU Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wu.ac.at\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wu.ac.at\\\/en\\\/tag\\\/diversitaet-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wu.ac.at\\\/en\\\/tag\\\/diversitaet-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.wu.ac.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diversit\u00e4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wu.ac.at\\\/#website\",\"url\":\"https:\\\/\\\/blog.wu.ac.at\\\/\",\"name\":\"WU Blog\",\"description\":\"Herzlich willkommen auf dem WU-Blog! Hier findet ihr eine Reihe an Blogbeitr\u00e4gen von Studierenden, ForscherInnen, Lehrenden, Alumni und MitarbeiterInnen - mach mit!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wu.ac.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diversit\u00e4t Archives - WU Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wu.ac.at\/en\/tag\/diversitaet-en\/","og_locale":"en_US","og_type":"article","og_title":"Diversit\u00e4t Archives - WU Blog","og_url":"https:\/\/blog.wu.ac.at\/en\/tag\/diversitaet-en\/","og_site_name":"WU Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.wu.ac.at\/en\/tag\/diversitaet-en\/","url":"https:\/\/blog.wu.ac.at\/en\/tag\/diversitaet-en\/","name":"Diversit\u00e4t Archives - WU Blog","isPartOf":{"@id":"https:\/\/blog.wu.ac.at\/#website"},"breadcrumb":{"@id":"https:\/\/blog.wu.ac.at\/en\/tag\/diversitaet-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wu.ac.at\/en\/tag\/diversitaet-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.wu.ac.at\/en\/"},{"@type":"ListItem","position":2,"name":"Diversit\u00e4t"}]},{"@type":"WebSite","@id":"https:\/\/blog.wu.ac.at\/#website","url":"https:\/\/blog.wu.ac.at\/","name":"WU Blog","description":"Herzlich willkommen auf dem WU-Blog! Hier findet ihr eine Reihe an Blogbeitr\u00e4gen von Studierenden, ForscherInnen, Lehrenden, Alumni und MitarbeiterInnen - mach mit!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wu.ac.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/blog.wu.ac.at\/en\/wp-json\/wp\/v2\/tags\/1868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wu.ac.at\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.wu.ac.at\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.wu.ac.at\/en\/wp-json\/wp\/v2\/posts?tags=1868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}